{"id":13,"date":"2020-07-15T14:22:00","date_gmt":"2020-07-15T14:22:00","guid":{"rendered":"http:\/\/sd-915358-h00018.ferozo.net\/ammercedes\/?page_id=13"},"modified":"2020-07-19T21:03:57","modified_gmt":"2020-07-19T21:03:57","slug":"contacto","status":"publish","type":"page","link":"https:\/\/cmgr.com.ar\/cmgr\/contacto\/","title":{"rendered":"Contacto"},"content":{"rendered":"<h3>Envianos un mail<\/h3>\n<div class=\"wpforms-container wpforms-container-full\" id=\"wpforms-15\"><form id=\"wpforms-form-15\" class=\"wpforms-validate wpforms-form\" data-formid=\"15\" method=\"post\" enctype=\"multipart\/form-data\" action=\"\/cmgr\/wp-json\/wp\/v2\/pages\/13\" data-token=\"cc6283952732981fd30b37cb888230f0\" data-token-time=\"1778708298\"><noscript class=\"wpforms-error-noscript\">Por favor, activa JavaScript en tu navegador para completar este formulario.<\/noscript><div class=\"wpforms-field-container\"><div id=\"wpforms-15-field_0-container\" class=\"wpforms-field wpforms-field-name\" data-field-id=\"0\"><label class=\"wpforms-field-label\" for=\"wpforms-15-field_0\">General <span class=\"wpforms-required-label\">*<\/span><\/label><div class=\"wpforms-field-row wpforms-field-medium\"><div class=\"wpforms-field-row-block wpforms-first wpforms-one-half\"><input type=\"text\" id=\"wpforms-15-field_0\" class=\"wpforms-field-name-first wpforms-field-required\" name=\"wpforms[fields][0][first]\" placeholder=\"Nombre\" required><label for=\"wpforms-15-field_0\" class=\"wpforms-field-sublabel after wpforms-sublabel-hide\">Nombre<\/label><\/div><div class=\"wpforms-field-row-block wpforms-one-half\"><input type=\"text\" id=\"wpforms-15-field_0-last\" class=\"wpforms-field-name-last wpforms-field-required\" name=\"wpforms[fields][0][last]\" placeholder=\"Apellido\" required><label for=\"wpforms-15-field_0-last\" class=\"wpforms-field-sublabel after wpforms-sublabel-hide\">Apellidos<\/label><\/div><\/div><\/div><div id=\"wpforms-15-field_1-container\" class=\"wpforms-field wpforms-field-email\" data-field-id=\"1\"><label class=\"wpforms-field-label\" for=\"wpforms-15-field_1\">Email <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"email\" id=\"wpforms-15-field_1\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][1]\" spellcheck=\"false\" required><\/div><div id=\"wpforms-15-field_3-container\" class=\"wpforms-field wpforms-field-text\" data-field-id=\"3\"><label class=\"wpforms-field-label\" for=\"wpforms-15-field_3\">Asunto <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"text\" id=\"wpforms-15-field_3\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][3]\" required><\/div><div id=\"wpforms-15-field_2-container\" class=\"wpforms-field wpforms-field-textarea\" data-field-id=\"2\"><label class=\"wpforms-field-label\" for=\"wpforms-15-field_2\">Comentario o mensaje <span class=\"wpforms-required-label\">*<\/span><\/label><textarea id=\"wpforms-15-field_2\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][2]\" required><\/textarea><\/div><\/div><!-- .wpforms-field-container --><div class=\"wpforms-field wpforms-field-hp\"><label for=\"wpforms-15-field-hp\" class=\"wpforms-field-label\">Message<\/label><input type=\"text\" name=\"wpforms[hp]\" id=\"wpforms-15-field-hp\" class=\"wpforms-field-medium\"><\/div><div class=\"wpforms-submit-container\" ><input type=\"hidden\" name=\"wpforms[id]\" value=\"15\"><input type=\"hidden\" name=\"page_title\" value=\"\"><input type=\"hidden\" name=\"page_url\" value=\"https:\/\/cmgr.com.ar\/cmgr\/wp-json\/wp\/v2\/pages\/13\"><button type=\"submit\" name=\"wpforms[submit]\" id=\"wpforms-submit-15\" class=\"wpforms-submit\" data-alt-text=\"Enviando...\" data-submit-text=\"Enviar\" aria-live=\"assertive\" value=\"wpforms-submit\">Enviar<\/button><\/div><\/form><\/div>  <!-- .wpforms-container -->\n<h3>O pod\u00e9s encontrarnos en&#8230;<\/h3>\n<p><iframe loading=\"lazy\" style=\"border: 0;\" tabindex=\"0\" src=\"https:\/\/www.google.com\/maps\/embed?pb=!1m14!1m8!1m3!1d13129.0137905044!2d-59.4303298!3d-34.6483017!3m2!1i1024!2i768!4f13.1!3m3!1m2!1s0x0%3A0xca716ab993aade5b!2sAsociacion%20Medica%20de%20Mercedes!5e0!3m2!1sen!2sar!4v1593987314717!5m2!1sen!2sar\" width=\"600\" height=\"450\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\" aria-hidden=\"false\"><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Envianos un mail O pod\u00e9s encontrarnos en&#8230;<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"_links":{"self":[{"href":"https:\/\/cmgr.com.ar\/cmgr\/wp-json\/wp\/v2\/pages\/13"}],"collection":[{"href":"https:\/\/cmgr.com.ar\/cmgr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/cmgr.com.ar\/cmgr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/cmgr.com.ar\/cmgr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/cmgr.com.ar\/cmgr\/wp-json\/wp\/v2\/comments?post=13"}],"version-history":[{"count":1,"href":"https:\/\/cmgr.com.ar\/cmgr\/wp-json\/wp\/v2\/pages\/13\/revisions"}],"predecessor-version":[{"id":1083,"href":"https:\/\/cmgr.com.ar\/cmgr\/wp-json\/wp\/v2\/pages\/13\/revisions\/1083"}],"wp:attachment":[{"href":"https:\/\/cmgr.com.ar\/cmgr\/wp-json\/wp\/v2\/media?parent=13"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}